{"id":356,"date":"2011-06-10T16:18:57","date_gmt":"2011-06-10T16:18:57","guid":{"rendered":"http:\/\/www.encontraaricanduva.com.br\/noticias\/?p=356"},"modified":"2013-08-12T18:34:54","modified_gmt":"2013-08-12T18:34:54","slug":"cat-movel-no-aricanduva-seleciona-profissionais-para-funcoes-de-apoio","status":"publish","type":"post","link":"https:\/\/www.encontraaricanduva.com.br\/sobre\/cat-movel-no-aricanduva-seleciona-profissionais-para-funcoes-de-apoio\/","title":{"rendered":"CAT m\u00f3vel no Aricanduva seleciona profissionais para fun\u00e7\u00f5es de apoio"},"content":{"rendered":"<div class=\"0761f6a77d7312e6c166bb5f335a15c5\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Entre os dias 13 e 15, as unidades do Centro de Apoio ao Trabalho (CAT)  selecionam 1.935 profissionais para fun\u00e7\u00f5es de apoio. S\u00e3o 1.556  oportunidades para auxiliares, 368 ajudantes e 11 assistentes.<\/p>\n<p>Est\u00e3o  sendo requisitados auxiliares de administra\u00e7\u00e3o, contabilidade,  almoxarifado, cobran\u00e7a, cozinha, enfermagem, escrit\u00f3rio, jardinagem,  limpeza, produ\u00e7\u00e3o, manuten\u00e7\u00e3o predial, mec\u00e2nicos e mec\u00e2nicos de  refrigera\u00e7\u00e3o. Para ajudante os cargos selecionados s\u00e3o: a\u00e7ougueiro,  carga e descarga, cozinheiro, padeiro, pintor, pizzaiolo, serralheiro,  administrador, contador e vendas. Como assistente s\u00e3o apenas 11 vagas  para quatro fun\u00e7\u00f5es: administrador, diretor de restaurante, contador e  vendedor.<\/p>\n<p>Para participar da sele\u00e7\u00e3o \u00e9 necess\u00e1ria experi\u00eancia  m\u00ednima de seis meses. A escolaridade varia de ensino fundamental, m\u00e9dio  ou superior, conforme a \u00e1rea de atua\u00e7\u00e3o pretendida e os sal\u00e1rios v\u00e3o de  R$ 600 a R$ 1.400, dependendo da empresa contratante.<\/p>\n<p>Os interessados devem comparecer a uma das unidades do CAT portando Carteira de Trabalho, RG e CPF.<\/p>\n<p><strong>Endere\u00e7os<\/strong><\/p>\n<p>CAT Luz<br \/>\nAv. Prestes Maia, 913 \/ 919<br \/>\nSegunda a sexta-feira: 7h \u00e0s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Itaquera<br \/>\nRua Greg\u00f3rio Ramalho, 12<br \/>\nSegunda a sexta-feira: 7h \u00e0s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Penha<br \/>\nRua Candapu\u00ed, 492 (dentro da Subprefeitura da Penha)<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Itaim Paulista<br \/>\nAv. Marechal Tito, 3.012<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT S\u00e3o Mateus I<br \/>\nAv. Mateo Bei, 1.641<br \/>\nSegunda a sexta-feira: 7h \u00e0s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT S\u00e3o Mateus II<br \/>\nRagueb Chohfi, 1.400<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Santana<br \/>\nRua Volunt\u00e1rios da P\u00e1tria, 1.553<br \/>\nSegunda a sexta-feira: 7h \u00e1s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Casa Verde<br \/>\nAv. Ordem e Progresso, 1.001<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Perus<br \/>\nRua Yl\u00eddio Figueiredo, 349<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Lapa<br \/>\nRua Monteiro de Melo, 342<br \/>\nSegunda a sexta-feira: 7h \u00e0s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Interlagos<br \/>\nAv. Interlagos, 6.122<br \/>\nSegunda a sexta-feira: 7h \u00e0s 18h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Jabaquara<br \/>\nAv. Eng. Armando de Arruda Pereira, 2.314<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Cidade Ademar<br \/>\nAv. Yervant Kissajikian, 416<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p>CAT Parelheiros<br \/>\nAv. Sadamu Inoue, 5.252<br \/>\nSegunda a sexta-feira: 8h \u00e0s 17h<br \/>\nS\u00e1bado: 7h \u00e0s 13h<\/p>\n<p><strong>Unidades M\u00f3veis<\/strong><\/p>\n<p>Subprefeitura de <strong>Aricanduva<\/strong>\/Vila Formosa\/Carr\u00e3o<br \/>\nRua Eponina, 82<\/p>\n<p>Cras Vila Prudente<br \/>\nRua Benedito Jacinto Mendes, 54<\/p>\n<p>Terminal de \u00d4nibus Lapa<br \/>\nRua Guaicurus, s\/n\u00ba<\/p>\n<p>Subprefeitura do Ja\u00e7an\u00e3\/Trememb\u00e9<br \/>\nAv. Luis Stamatis, 300)<\/p>\n<p>Esta\u00e7\u00e3o do metr\u00f4 Barra Funda<br \/>\nRua Prof. Wilfrides Alves de Lima<\/p>\n<p>Subprefeitura de Vila Mariana<br \/>\nRua Jos\u00e9 de Magalh\u00e3es, 500<\/p>\n<p>CAT Itinerante \u2013 Tenda do Trabalhador<br \/>\nVale do Anhangaba\u00fa (em frente ao pr\u00e9dio dos Correios)<\/p>\n<p><em>Fonte: Prefeitura de S\u00e3o Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Entre os dias 13 e 15, as unidades do Centro de Apoio ao Trabalho (CAT) selecionam 1.935 profissionais para fun\u00e7\u00f5es de apoio. S\u00e3o 1.556 oportunidades para auxiliares, 368 ajudantes e 11 assistentes. Est\u00e3o sendo requisitados auxiliares de administra\u00e7\u00e3o, contabilidade, almoxarifado, cobran\u00e7a, cozinha, enfermagem, escrit\u00f3rio, jardinagem, limpeza, produ\u00e7\u00e3o, manuten\u00e7\u00e3o predial, mec\u00e2nicos e mec\u00e2nicos de refrigera\u00e7\u00e3o. Para ajudante os cargos selecionados s\u00e3o: a\u00e7ougueiro, carga e descarga, cozinheiro, padeiro, pintor, pizzaiolo, serralheiro, administrador, contador e vendas. Como assistente s\u00e3o apenas 11 vagas para quatro fun\u00e7\u00f5es: administrador, diretor de restaurante, contador e vendedor. Para participar da sele\u00e7\u00e3o \u00e9 necess\u00e1ria experi\u00eancia m\u00ednima de seis meses. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-356","post","type-post","status-publish","format-standard","hentry","category-noticias-no-aricanduva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}