{"id":340,"date":"2011-05-30T06:13:42","date_gmt":"2011-05-30T06:13:42","guid":{"rendered":"http:\/\/www.encontraaricanduva.com.br\/noticias\/?p=340"},"modified":"2013-08-12T18:30:58","modified_gmt":"2013-08-12T18:30:58","slug":"aricanduva-confrontos-com-a-policia-terminam-com-dois-mortos-e-quatro-detidos","status":"publish","type":"post","link":"https:\/\/www.encontraaricanduva.com.br\/sobre\/aricanduva-confrontos-com-a-policia-terminam-com-dois-mortos-e-quatro-detidos\/","title":{"rendered":"Aricanduva: Confrontos com a pol\u00edcia terminam com dois mortos e quatro detidos"},"content":{"rendered":"<div class=\"0761f6a77d7312e6c166bb5f335a15c5\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Dois bandidos foram mortos e quatro adolescentes, seus comparsas, foram detidos em S\u00e3o Paulo em dois casos de suposta resist\u00eancia seguida de morte, no domingo (29). Os casos s\u00e3o investigados pelo DHPP (Departamento de Homic\u00eddios e Prote\u00e7\u00e3o \u00e0 Pessoa).<\/p>\n<p>Em uma LAN houve, houve um tiroteio com a PM\u00a0depois que um trio tentou assaltar o estabelecimento localizado na altura do n\u00famero 2.559 da avenida Itaquera, em Artur Alvim, zona leste de S\u00e3o Paulo. Um homem acabou morto na troca de tiros com a PM, quando era atendido no pronto-socorro da Vila Nhocun\u00e9.<\/p>\n<p>Os dois menores n\u00e3o resistiram \u00e0 voz de pris\u00e3o e foram detidos. O caso foi registrado no 66\u00ba DP (Distrito Policial), do Vale do Aricanduva e agoa \u00e9 investigado pelo DHPP por se tratar de uma suposta resist\u00eancia seguida de morte.<\/p>\n<p>Na rodovia Presidente Dutra,\u00a0um adolescente de 16 anos morreu em uma troca de tiros com policiais militares no km 230, no bairro de Vila Maria, na zona norte de S\u00e3o Paulo, no fim da tarde de domingo. Ele e outros dois adolescentes ocupavam um carro roubado.<\/p>\n<p>A ca\u00e7a aos suspeitos come\u00e7ou na rodovia Fern\u00e3o Dias e terminou na Dutra ap\u00f3s uma batida. O adolescente, armado, teria atirado contra os policiais e levou a pior, morrendo dentro do carro. O caso foi registrado no 9\u00ba DP (Distrito Policial).<\/p>\n<p><em>Fonte: R7<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Dois bandidos foram mortos e quatro adolescentes, seus comparsas, foram detidos em S\u00e3o Paulo em dois casos de suposta resist\u00eancia seguida de morte, no domingo (29). Os casos s\u00e3o investigados pelo DHPP (Departamento de Homic\u00eddios e Prote\u00e7\u00e3o \u00e0 Pessoa). Em uma LAN houve, houve um tiroteio com a PM\u00a0depois que um trio tentou assaltar o estabelecimento localizado na altura do n\u00famero 2.559 da avenida Itaquera, em Artur Alvim, zona leste de S\u00e3o Paulo. Um homem acabou morto na troca de tiros com a PM, quando era atendido no pronto-socorro da Vila Nhocun\u00e9. Os dois menores n\u00e3o resistiram \u00e0 voz de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-340","post","type-post","status-publish","format-standard","hentry","category-noticias-no-aricanduva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=340"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/340\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}