{"id":1287,"date":"2013-06-07T00:39:29","date_gmt":"2013-06-07T00:39:29","guid":{"rendered":"http:\/\/www.encontraaricanduva.com.br\/noticias\/?p=1287"},"modified":"2013-08-12T18:33:23","modified_gmt":"2013-08-12T18:33:23","slug":"operacao-cata-bagulho-acontece-sabado-0806-em-aricanduva","status":"publish","type":"post","link":"https:\/\/www.encontraaricanduva.com.br\/sobre\/operacao-cata-bagulho-acontece-sabado-0806-em-aricanduva\/","title":{"rendered":"Opera\u00e7\u00e3o Cata-bagulho acontece s\u00e1bado (08\/06) em Aricanduva"},"content":{"rendered":"<div class=\"0761f6a77d7312e6c166bb5f335a15c5\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Equipes da <a title=\"Subprefeitura Aricanduva\/Formosa\/Carr\u00e3o\" href=\"http:\/\/www.encontraaricanduva.com.br\/aricanduva\/subprefeitura-do-aricanduva.shtml\" target=\"_blank\">Subprefeitura Aricanduva\/Formosa\/Carr\u00e3o<\/a> percorrer\u00e3o as ruas da regi\u00e3o para mais uma opera\u00e7\u00e3o Cata-bagulho.<\/p>\n<p>A a\u00e7\u00e3o acontece s\u00e1bado (08\/06).<\/p>\n<p>Ser\u00e3o recolhidos materiais inserv\u00edveis, como m\u00f3veis velhos, eletrodom\u00e9sticos quebrados, madeiras e utens\u00edlios dom\u00e9sticos. O per\u00edmetro atendido fica entre a Avenida Aricanduva (lado par \u2013 entre Av. Mazaropi e Av. Arraias do Araguaia), Av. Arraias do Araguaia (entre Av. Aricanduva e Av. Pastor C\u00edcero Canuto de Lima) , Av. Pastor C\u00edcero Canuto de Lima (toda extens\u00e3o) ,Av. dos Nacionalistas (toda extens\u00e3o), Av. Aguiar da Beira (entre Av. dos Nacionalistas e Av. Ver. Em\u00edlio Meneguini) , Av. Em\u00edlio Meneguini (toda extens\u00e3o) e Av. Mazaropi (toda extens\u00e3o).<\/p>\n<p>\u00c9 importante que o mun\u00edcipe coloque os objetos a serem recolhidos nas cal\u00e7adas at\u00e9 as 09 horas.<\/p>\n<p>Um dos objetivos da a\u00e7\u00e3o \u00e9 impedir que os materiais sem uso sejam descartados em vias p\u00fablicas, comprometendo o escoamento da \u00e1gua em dias de chuva, que pode gerar alagamentos e enchentes. O servi\u00e7o de cata-bagulho recolheu, no \u00faltimo trimestre mais de 75 toneladas de objetos inserv\u00edveis.<\/p>\n<p>As opera\u00e7\u00f5es Cata-bagulho n\u00e3o fazem recolhimento de entulho. Para esses casos, pequenas quantidades de at\u00e9 1 m\u00b3 de entulho &#8211; que corresponde a uma caixa d&#8217;\u00e1gua de mil litros ou 25% de uma ca\u00e7amba &#8211; gerados por pequenas reformas e constru\u00e7\u00f5es, podem ser levados gratuitamente para os Ecopontos da regi\u00e3o.<\/p>\n<p>Quem gera muito entulho deve contratar uma empresa especializada em servi\u00e7os de coleta e transporte de entulho, cadastrada pela Prefeitura, que faz o descarte de forma apropriada em aterros de inertes. O cidad\u00e3o pode conferir a rela\u00e7\u00e3o das empresas cadastradas no site prefeitura.sp.gov.br.<\/p>\n<p><strong>Servi\u00e7o no bairro de Aricanduva:<\/strong><\/p>\n<p>Opera\u00e7\u00e3o Cata-bagulho no bairro de Aricanduva.<\/p>\n<p><strong>Data:\u00a0<\/strong>08 de\u00a0junho de 2013<\/p>\n<p><strong>Hor\u00e1rio:<\/strong>\u00a010h00 \u00e0s 16h00<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<strong><br \/>\n<\/strong><\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Equipes da Subprefeitura Aricanduva\/Formosa\/Carr\u00e3o percorrer\u00e3o as ruas da regi\u00e3o para mais uma opera\u00e7\u00e3o Cata-bagulho. A a\u00e7\u00e3o acontece s\u00e1bado (08\/06). Ser\u00e3o recolhidos materiais inserv\u00edveis, como m\u00f3veis velhos, eletrodom\u00e9sticos quebrados, madeiras e utens\u00edlios dom\u00e9sticos. O per\u00edmetro atendido fica entre a Avenida Aricanduva (lado par \u2013 entre Av. Mazaropi e Av. Arraias do Araguaia), Av. Arraias do Araguaia (entre Av. Aricanduva e Av. Pastor C\u00edcero Canuto de Lima) , Av. Pastor C\u00edcero Canuto de Lima (toda extens\u00e3o) ,Av. dos Nacionalistas (toda extens\u00e3o), Av. Aguiar da Beira (entre Av. dos Nacionalistas e Av. Ver. Em\u00edlio Meneguini) , Av. Em\u00edlio Meneguini (toda extens\u00e3o) e Av. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1287","post","type-post","status-publish","format-standard","hentry","category-noticias-no-aricanduva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1287"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1287\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}