{"id":1177,"date":"2013-02-08T21:33:03","date_gmt":"2013-02-08T21:33:03","guid":{"rendered":"http:\/\/www.encontraaricanduva.com.br\/noticias\/?p=1177"},"modified":"2013-08-12T18:32:26","modified_gmt":"2013-08-12T18:32:26","slug":"operacao-cata-bagulho-percorre-bairro-do-aricanduva-no-sabado-de-carnaval","status":"publish","type":"post","link":"https:\/\/www.encontraaricanduva.com.br\/sobre\/operacao-cata-bagulho-percorre-bairro-do-aricanduva-no-sabado-de-carnaval\/","title":{"rendered":"Opera\u00e7\u00e3o Cata-Bagulho percorre bairro do Aricanduva no s\u00e1bado de Carnaval"},"content":{"rendered":"<div class=\"0761f6a77d7312e6c166bb5f335a15c5\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Neste s\u00e1bado de Carnaval (9\/2), das 6h30 \u00e0s 18h, 23 Subprefeituras da cidade realizam a Opera\u00e7\u00e3o Cata-Bagulho. As equipes de limpeza v\u00e3o recolher m\u00f3veis velhos, madeiras, eletrodom\u00e9sticos quebrados, colch\u00f5es, entre outros materiais em desuso. A opera\u00e7\u00e3o tem o objetivo de retirar os materiais que j\u00e1 n\u00e3o tem mais utilidade para a popula\u00e7\u00e3o, dando uma destina\u00e7\u00e3o correta e evitando o descarte irregular em lugares inapropriados.<\/p>\n<p>Lembramos que o descarte irregular \u00e9 considerado crime ambiental e pass\u00edvel de multa de R$ 13 mil, por isso se algum mun\u00edcipe quiser descartar algum material em desuso, mas n\u00e3o teve a sua via contemplada nesta opera\u00e7\u00e3o, \u00e9 s\u00f3 solicitar que a Subprefeitura de sua regi\u00e3o inclua sua rua nas pr\u00f3ximas a\u00e7\u00f5es pelo telefone 156, ou se dirigir a um dos Ecopontos espalhados pela cidade.<\/p>\n<p>Os moradores que quiserem realizar o descarte devem colocar os objetos em suas cal\u00e7adas, atentando para os hor\u00e1rios e vias percorridas, de acordo com a programa\u00e7\u00e3o abaixo.<\/p>\n<p><strong>Confira os locais por onde passar\u00e1 o servi\u00e7o no bairro de Aricanduva<\/strong><\/p>\n<p><strong>Aricanduva: das 10h \u00e0s 18h<\/strong><br \/>\nOnde: Av. Jo\u00e3o XXIII (toda extens\u00e3o), Rua Ang\u00e1 (entre Av. Jo\u00e3o XXIII e Rua S\u00e3o Ticiano), Rua S\u00e3o Ticiano (toda extens\u00e3o), Pra\u00e7a Tadashi Nishii, Rua Arac\u00ea (entre Pra\u00e7a Tadashi Nishii e Rua V\u00eanus), Rua V\u00eanus (entre Rua Arac\u00ea e Av. Dedo de Deus) , Av. Dedo de Deus (toda extens\u00e3o), Rua Taubat\u00e9 (toda extens\u00e3o) e Av. 19 de Janeiro (entre a Rua Taubat\u00e9 e Av. Jo\u00e3o XXIII).<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado de Carnaval (9\/2), das 6h30 \u00e0s 18h, 23 Subprefeituras da cidade realizam a Opera\u00e7\u00e3o Cata-Bagulho. As equipes de limpeza v\u00e3o recolher m\u00f3veis velhos, madeiras, eletrodom\u00e9sticos quebrados, colch\u00f5es, entre outros materiais em desuso. A opera\u00e7\u00e3o tem o objetivo de retirar os materiais que j\u00e1 n\u00e3o tem mais utilidade para a popula\u00e7\u00e3o, dando uma destina\u00e7\u00e3o correta e evitando o descarte irregular em lugares inapropriados. Lembramos que o descarte irregular \u00e9 considerado crime ambiental e pass\u00edvel de multa de R$ 13 mil, por isso se algum mun\u00edcipe quiser descartar algum material em desuso, mas n\u00e3o teve a sua via contemplada nesta <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1177","post","type-post","status-publish","format-standard","hentry","category-noticias-no-aricanduva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraaricanduva.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}